{"id":53,"count":24,"description":"<h1>News<\/h1>","link":"https:\/\/skapoultryequipment.com\/es\/category\/news-es\/","name":"News","slug":"news-es","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>News - SKA Poultry Equipment<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/skapoultryequipment.com\/es\/category\/news-es\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"News - SKA Poultry Equipment\" \/>\n<meta property=\"og:description\" content=\"News\" \/>\n<meta property=\"og:url\" content=\"https:\/\/skapoultryequipment.com\/es\/category\/news-es\/\" \/>\n<meta property=\"og:site_name\" content=\"SKA Poultry Equipment\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/skapoultryequipment.com\/es\/category\/news-es\/\",\"url\":\"https:\/\/skapoultryequipment.com\/es\/category\/news-es\/\",\"name\":\"News - SKA Poultry Equipment\",\"isPartOf\":{\"@id\":\"https:\/\/skapoultryequipment.com\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/skapoultryequipment.com\/es\/category\/news-es\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/skapoultryequipment.com\/es\/category\/news-es\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/skapoultryequipment.com\/es\/home\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/skapoultryequipment.com\/#website\",\"url\":\"https:\/\/skapoultryequipment.com\/\",\"name\":\"SKA Poultry Equipment\",\"description\":\"SKA azienda leader nel settore della progettazione e produzione di impianti ed attrezzature per l&#039;allevamento avicolo a terra.\",\"publisher\":{\"@id\":\"https:\/\/skapoultryequipment.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/skapoultryequipment.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/skapoultryequipment.com\/#organization\",\"name\":\"SKA S.r.l.\",\"url\":\"https:\/\/skapoultryequipment.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/skapoultryequipment.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/skapoultryequipment.com\/wp-content\/uploads\/2020\/09\/logo-SKA.png\",\"contentUrl\":\"https:\/\/skapoultryequipment.com\/wp-content\/uploads\/2020\/09\/logo-SKA.png\",\"width\":183,\"height\":183,\"caption\":\"SKA S.r.l.\"},\"image\":{\"@id\":\"https:\/\/skapoultryequipment.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"News - SKA Poultry Equipment","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/skapoultryequipment.com\/es\/category\/news-es\/","og_locale":"es_ES","og_type":"article","og_title":"News - SKA Poultry Equipment","og_description":"News","og_url":"https:\/\/skapoultryequipment.com\/es\/category\/news-es\/","og_site_name":"SKA Poultry Equipment","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/skapoultryequipment.com\/es\/category\/news-es\/","url":"https:\/\/skapoultryequipment.com\/es\/category\/news-es\/","name":"News - SKA Poultry Equipment","isPartOf":{"@id":"https:\/\/skapoultryequipment.com\/#website"},"breadcrumb":{"@id":"https:\/\/skapoultryequipment.com\/es\/category\/news-es\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/skapoultryequipment.com\/es\/category\/news-es\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/skapoultryequipment.com\/es\/home\/"},{"@type":"ListItem","position":2,"name":"News"}]},{"@type":"WebSite","@id":"https:\/\/skapoultryequipment.com\/#website","url":"https:\/\/skapoultryequipment.com\/","name":"SKA Poultry Equipment","description":"SKA azienda leader nel settore della progettazione e produzione di impianti ed attrezzature per l&#039;allevamento avicolo a terra.","publisher":{"@id":"https:\/\/skapoultryequipment.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/skapoultryequipment.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/skapoultryequipment.com\/#organization","name":"SKA S.r.l.","url":"https:\/\/skapoultryequipment.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/skapoultryequipment.com\/#\/schema\/logo\/image\/","url":"https:\/\/skapoultryequipment.com\/wp-content\/uploads\/2020\/09\/logo-SKA.png","contentUrl":"https:\/\/skapoultryequipment.com\/wp-content\/uploads\/2020\/09\/logo-SKA.png","width":183,"height":183,"caption":"SKA S.r.l."},"image":{"@id":"https:\/\/skapoultryequipment.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/skapoultryequipment.com\/es\/wp-json\/wp\/v2\/categories\/53"}],"collection":[{"href":"https:\/\/skapoultryequipment.com\/es\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/skapoultryequipment.com\/es\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/skapoultryequipment.com\/es\/wp-json\/wp\/v2\/posts?categories=53"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}